{"id":90,"date":"2017-07-18T12:35:39","date_gmt":"2017-07-18T12:35:39","guid":{"rendered":"https:\/\/softfardamentos.com.br\/?page_id=90"},"modified":"2022-09-10T12:22:33","modified_gmt":"2022-09-10T12:22:33","slug":"home-1","status":"publish","type":"page","link":"https:\/\/softfardamentos.com.br\/","title":{"rendered":"Soft Fardamentos"},"content":{"rendered":"<p>[vc_row full_width=&#8221;stretch_row_content_no_spaces&#8221; hide_bg_image_on_tablet=&#8221;&#8221; hide_bg_image_on_mobile=&#8221;&#8221;][vc_column][rev_slider_vc alias=&#8221;home-1&#8243;][\/vc_column][\/vc_row][vc_row content_placement=&#8221;middle&#8221; hide_bg_image_on_tablet=&#8221;&#8221; hide_bg_image_on_mobile=&#8221;&#8221;][vc_column]<div class=\"sc_layouts sc_layouts_default sc_layouts_686\">[vc_row content_placement=\"middle\" hide_bg_image_on_tablet=\"\" hide_bg_image_on_mobile=\"\"][vc_column icons_position=\"left\"][vc_empty_space alter_height=\"huge\" hide_on_desktop=\"\" hide_on_notebook=\"\" hide_on_tablet=\"\" hide_on_mobile=\"\"][\/vc_column][vc_column width=\"1\/2\" icons_position=\"left\"]<div id=\"home_swiper\" class=\"widget_area sc_widget_slider vc_widget_slider wpb_content_element\"><aside id=\"home_swiper_widget\" class=\"widget widget_slider\">\t\t\t<div class=\"slider_wrap slider_engine_swiper\">\n\t\t\t\t<div id=\"home_swiper_outer\" class=\"slider_outer slider_swiper_outer slider_style_default slider_outer_direction_horizontal slider_outer_one slider_outer_pagination slider_outer_pagination_bullets slider_outer_pagination_pos_left_outside slider_outer_nocontrols slider_outer_titles_center\"><div id=\"home_swiper_swiper\" class=\"slider_container slider_swiper swiper-slider-container slider_nocontrols slider_titles_center slider_noresize slider_height_auto slider_direction_horizontal slider_pagination slider_pagination_bullets slider_pagination_pos_left_outside slider_one slider_type_images\" data-ratio=\"16:9\" data-interval=\"7000\" data-effect=\"slide\" data-pagination=\"bullets\" data-direction=\"horizontal\" data-slides-per-view=\"1\" data-slides-space=\"8\"><div class=\"slider-wrapper swiper-wrapper\"><div  class=\"slider-slide swiper-slide\" data-image=\"https:\/\/softfardamentos.com.br\/wp-content\/uploads\/2017\/10\/uni6.jpg\" style=\"\"><img decoding=\"async\" src=\"https:\/\/softfardamentos.com.br\/wp-content\/uploads\/2017\/10\/uni6.jpg\" alt=\"\"><\/div><div  class=\"slider-slide swiper-slide\" data-image=\"https:\/\/softfardamentos.com.br\/wp-content\/uploads\/2017\/10\/uni5.jpg\" style=\"\"><img decoding=\"async\" src=\"https:\/\/softfardamentos.com.br\/wp-content\/uploads\/2017\/10\/uni5.jpg\" alt=\"\"><\/div><div  class=\"slider-slide swiper-slide\" data-image=\"https:\/\/softfardamentos.com.br\/wp-content\/uploads\/2017\/10\/ui7.jpg\" style=\"\"><img decoding=\"async\" src=\"https:\/\/softfardamentos.com.br\/wp-content\/uploads\/2017\/10\/ui7.jpg\" alt=\"\"><\/div><\/div><!-- \/.slider-wrapper --><\/div><!-- \/.slider_swiper --><div class=\"slider_pagination_wrap swiper-pagination\"><\/div><\/div><!-- \/.slider_outer -->\t\t\t<\/div>\n\t\t\t<\/aside><\/div>[\/vc_column][vc_column width=\"1\/2\" hide_bg_image_on_tablet=\"\" hide_bg_image_on_mobile=\"\" icons_position=\"left\" offset=\"vc_col-sm-offset-0\" css=\".vc_custom_1662808562960{margin-top: -50px !important;border-top-width: -50px !important;padding-top: -50px !important;}\"]<div id=\"sc_title_606801971\"\n\t\tclass=\"sc_title color_style_default sc_title_default\"><h6 class=\"sc_item_subtitle sc_title_subtitle sc_align_center sc_item_title_style_default\">N\u00f3s somos a<\/h6><h2 class=\"sc_item_title sc_title_title sc_align_center sc_item_title_style_default sc_item_title_tag\">Soft Fardamentos EPI's<\/h2><div class=\"sc_item_descr sc_title_descr sc_align_center\"><p>Uniformes Profissionais de qualidade com inova\u00e7\u00e3o e confiabilidade, a Soft Fardamentos sabe que para alcan\u00e7ar excel\u00eancia em sua categoria \u00e9 preciso estar sempre cuidando de sua conduta e seu desempenho.<br \/>\nPara isso, estipulamos miss\u00f5es, metas e valores que acreditamos serem fundamentais para a empresa, clientes e colaboradores.<\/p>\n<\/div><div class=\"sc_item_button sc_button_wrap sc_align_center\"><a href=\"\/contacts\/\" id=\"sc_button_1957692119\" class=\"sc_button color_style_default sc_button_default sc_item_button sc_item_button_default sc_title_button sc_button_size_normal sc_button_icon_left\"><span class=\"sc_button_text\"><span class=\"sc_button_title\">Fa\u00e7a um or\u00e7amento<\/span><\/span><!-- \/.sc_button_text --><\/a><!-- \/.sc_button --><\/div><!-- \/.sc_item_button --><\/div><!-- \/.sc_title -->[\/vc_column][vc_column icons_position=\"left\"][vc_empty_space alter_height=\"huge\" hide_on_desktop=\"\" hide_on_notebook=\"\" hide_on_tablet=\"\" hide_on_mobile=\"\" css=\".vc_custom_1507624024636{margin-top: -0.3rem !important;}\"][\/vc_column][\/vc_row]<\/div>[\/vc_column][\/vc_row][vc_row content_placement=&#8221;middle&#8221; hide_bg_image_on_tablet=&#8221;&#8221; hide_bg_image_on_mobile=&#8221;&#8221;][vc_column]<div class=\"sc_layouts sc_layouts_default sc_layouts_687\">[vc_row full_width=\"stretch_row\" hide_bg_image_on_tablet=\"\" hide_bg_image_on_mobile=\"\" css=\".vc_custom_1662810341619{background-color: #efefef !important;background-size: cover !important;}\"][vc_column icons_position=\"left\"][vc_empty_space height=\"40\" hide_on_desktop=\"\" hide_on_notebook=\"\" hide_on_tablet=\"\" hide_on_mobile=\"\"]<div id=\"sc_title_372442799\"\n\t\tclass=\"sc_title color_style_default sc_title_default\"><h3 class=\"sc_item_title sc_title_title sc_align_left sc_item_title_style_default\">Qualidade e Seguran\u00e7a para sua Empresa<\/h3><div class=\"sc_item_descr sc_title_descr sc_align_left\"><p>Uniformize sua equipe com os melhores uniformes em Curitiba. Possu\u00edmos uma gama enorme de produtos onde temos de tudo para a sua prote\u00e7\u00e3o e uniformiza\u00e7\u00e3o.<\/p>\n<\/div><\/div><!-- \/.sc_title -->[vc_row_inner hide_bg_image_on_tablet=\"\" hide_bg_image_on_mobile=\"\" css=\".vc_custom_1662810370883{margin-bottom: 60px !important;border-bottom-width: 60px !important;padding-bottom: 60px !important;}\"][vc_column_inner width=\"1\/3\" icons_position=\"left\"][vc_icon icon_fontawesome=\"icon-diamond-light\" size=\"lg\" align=\"center\"][vc_custom_heading text=\"QUALIDADE SUPERIOR\" font_container=\"tag:h5|text_align:center\" use_theme_fonts=\"yes\" css=\".vc_custom_1662810026694{margin-top: -30px !important;}\"][vc_column_text]\r\n<p style=\"text-align: center;\">Nossas pe\u00e7as possuem acabamento impec\u00e1vel, costura resistente e tecidos de alta qualidade.<\/p>\r\n[\/vc_column_text][\/vc_column_inner][vc_column_inner width=\"1\/3\" icons_position=\"left\"][vc_icon icon_fontawesome=\"fas fa-hand-holding-usd\" size=\"lg\" align=\"center\"][vc_custom_heading text=\"\u00d3TIMOS PRE\u00c7OS\" font_container=\"tag:h5|text_align:center\" use_theme_fonts=\"yes\" css=\".vc_custom_1662810055102{margin-top: -30px !important;}\"][vc_column_text]\r\n<p style=\"text-align: center;\">Nossos uniformes tem imensa durabilidade, conforto, estilo e modelagem \u00fanica com pre\u00e7o justo.<\/p>\r\n[\/vc_column_text][\/vc_column_inner][vc_column_inner width=\"1\/3\" icons_position=\"left\"][vc_icon icon_fontawesome=\"icon-star\" size=\"lg\" align=\"center\"][vc_custom_heading text=\"LINHA COMPLETA\" font_container=\"tag:h5|text_align:center\" use_theme_fonts=\"yes\" css=\".vc_custom_1662810202602{margin-top: -30px !important;}\"][vc_column_text]\r\n<p style=\"text-align: center;\">Contamos com uma linha completa de camisas, cal\u00e7as, polos, camisetas, jalecos e muito mais.<\/p>\r\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_empty_space height=\"250\" hide_on_desktop=\"\" hide_on_notebook=\"\" hide_on_tablet=\"\" hide_on_mobile=\"\"][\/vc_column][\/vc_row]<\/div>[\/vc_column][\/vc_row][vc_row][vc_column]<div class=\"sc_layouts sc_layouts_default sc_layouts_419\">[vc_row full_width=\"stretch_row\" hide_bg_image_on_tablet=\"\" hide_bg_image_on_mobile=\"\" css=\".vc_custom_1662810538741{background-color: #061356 !important;background-size: cover !important;}\"][vc_column icons_position=\"left\"][vc_empty_space alter_height=\"medium\" hide_on_desktop=\"\" hide_on_notebook=\"\" hide_on_tablet=\"\" hide_on_mobile=\"\" css=\".vc_custom_1507299344538{margin-top: 0.3rem !important;}\"][vc_empty_space alter_height=\"huge\" hide_on_desktop=\"\" hide_on_notebook=\"\" hide_on_tablet=\"\" hide_on_mobile=\"\"]<div id=\"sc_title_941089486\"\n\t\tclass=\"sc_title  no_underscore color_style_default scheme_dark sc_title_default\"><h3 class=\"sc_item_title sc_title_title sc_align_center sc_item_title_style_default\">A melhor escolha em uniformes profissionais e EPI's<\/h3><div class=\"sc_item_descr sc_title_descr sc_align_center\"><p>Aqui voc\u00ea encontra o que h\u00e1 de melhor em Camisas e Cal\u00e7as para uniformes profissionais para sua empresa!<\/p>\n<\/div><\/div><!-- \/.sc_title -->[vc_empty_space alter_height=\"huge\" hide_on_desktop=\"\" hide_on_notebook=\"\" hide_on_tablet=\"\" hide_on_mobile=\"\" css=\".vc_custom_1507299790131{margin-top: -0.5rem !important;}\"]<style type=\"text\/css\">a.eg-henryharrison-element-1,a.eg-henryharrison-element-2{-webkit-transition:all .4s linear;   -moz-transition:all .4s linear;   -o-transition:all .4s linear;   -ms-transition:all .4s linear;   transition:all .4s linear}.eg-jimmy-carter-element-11 i:before{margin-left:0px; margin-right:0px}.eg-harding-element-17{letter-spacing:1px}.eg-harding-wrapper .esg-entry-media{overflow:hidden; box-sizing:border-box;   -webkit-box-sizing:border-box;   -moz-box-sizing:border-box;   padding:30px 30px 0px 30px}.eg-harding-wrapper .esg-media-poster{overflow:hidden; border-radius:50%;   -webkit-border-radius:50%;   -moz-border-radius:50%}.eg-ulysses-s-grant-wrapper .esg-entry-media{overflow:hidden; box-sizing:border-box;   -webkit-box-sizing:border-box;   -moz-box-sizing:border-box;   padding:30px 30px 0px 30px}.eg-ulysses-s-grant-wrapper .esg-media-poster{overflow:hidden; border-radius:50%;   -webkit-border-radius:50%;   -moz-border-radius:50%}.eg-richard-nixon-wrapper .esg-entry-media{overflow:hidden; box-sizing:border-box;   -webkit-box-sizing:border-box;   -moz-box-sizing:border-box;   padding:30px 30px 0px 30px}.eg-richard-nixon-wrapper .esg-media-poster{overflow:hidden; border-radius:50%;   -webkit-border-radius:50%;   -moz-border-radius:50%}.eg-herbert-hoover-wrapper .esg-media-poster{filter:url(\"data:image\/svg+xml;utf8,<svg xmlns='http:\/\/www.w3.org\/2000\/svg'><filter id='grayscale'><feColorMatrix type='matrix' values='0.3333 0.3333 0.3333 0 0 0.3333 0.3333 0.3333 0 0 0.3333 0.3333 0.3333 0 0 0 0 0 1 0'\/><\/filter><\/svg>#grayscale\");   filter:gray;   -webkit-filter:grayscale(100%)}.eg-herbert-hoover-wrapper:hover .esg-media-poster{filter:url(\"data:image\/svg+xml;utf8,<svg xmlns='http:\/\/www.w3.org\/2000\/svg'><filter id='grayscale'><feColorMatrix type='matrix' values='1 0 0 0 0,0 1 0 0 0,0 0 1 0 0,0 0 0 1 0'\/><\/filter><\/svg>#grayscale\");  -webkit-filter:grayscale(0%)}.eg-lyndon-johnson-wrapper .esg-media-poster{filter:url(\"data:image\/svg+xml;utf8,<svg xmlns='http:\/\/www.w3.org\/2000\/svg'><filter id='grayscale'><feColorMatrix type='matrix' values='0.3333 0.3333 0.3333 0 0 0.3333 0.3333 0.3333 0 0 0.3333 0.3333 0.3333 0 0 0 0 0 1 0'\/><\/filter><\/svg>#grayscale\");   filter:gray;   -webkit-filter:grayscale(100%)}.eg-lyndon-johnson-wrapper:hover .esg-media-poster{filter:url(\"data:image\/svg+xml;utf8,<svg xmlns='http:\/\/www.w3.org\/2000\/svg'><filter id='grayscale'><feColorMatrix type='matrix' values='1 0 0 0 0,0 1 0 0 0,0 0 1 0 0,0 0 0 1 0'\/><\/filter><\/svg>#grayscale\");  -webkit-filter:grayscale(0%)}.esg-overlay.eg-ronald-reagan-container{background:-moz-linear-gradient(top,rgba(0,0,0,0) 50%,rgba(0,0,0,0.83) 99%,rgba(0,0,0,0.85) 100%); background:-webkit-gradient(linear,left top,left bottom,color-stop(50%,rgba(0,0,0,0)),color-stop(99%,rgba(0,0,0,0.83)),color-stop(100%,rgba(0,0,0,0.85))); background:-webkit-linear-gradient(top,rgba(0,0,0,0) 50%,rgba(0,0,0,0.83) 99%,rgba(0,0,0,0.85) 100%); background:-o-linear-gradient(top,rgba(0,0,0,0) 50%,rgba(0,0,0,0.83) 99%,rgba(0,0,0,0.85) 100%); background:-ms-linear-gradient(top,rgba(0,0,0,0) 50%,rgba(0,0,0,0.83) 99%,rgba(0,0,0,0.85) 100%); background:linear-gradient(to bottom,rgba(0,0,0,0) 50%,rgba(0,0,0,0.83) 99%,rgba(0,0,0,0.85) 100%); filter:progid:DXImageTransform.Microsoft.gradient( startColorstr='#00000000',endColorstr='#d9000000',GradientType=0 )}.eg-georgebush-wrapper .esg-entry-cover{background:-moz-linear-gradient(top,rgba(0,0,0,0) 50%,rgba(0,0,0,0.83) 99%,rgba(0,0,0,0.85) 100%); background:-webkit-gradient(linear,left top,left bottom,color-stop(50%,rgba(0,0,0,0)),color-stop(99%,rgba(0,0,0,0.83)),color-stop(100%,rgba(0,0,0,0.85))); background:-webkit-linear-gradient(top,rgba(0,0,0,0) 50%,rgba(0,0,0,0.83) 99%,rgba(0,0,0,0.85) 100%); background:-o-linear-gradient(top,rgba(0,0,0,0) 50%,rgba(0,0,0,0.83) 99%,rgba(0,0,0,0.85) 100%); background:-ms-linear-gradient(top,rgba(0,0,0,0) 50%,rgba(0,0,0,0.83) 99%,rgba(0,0,0,0.85) 100%); background:linear-gradient(to bottom,rgba(0,0,0,0) 50%,rgba(0,0,0,0.83) 99%,rgba(0,0,0,0.85) 100%); filter:progid:DXImageTransform.Microsoft.gradient( startColorstr='#00000000',endColorstr='#d9000000',GradientType=0 )}.eg-jefferson-wrapper{-webkit-border-radius:5px !important; -moz-border-radius:5px !important; border-radius:5px !important; -webkit-mask-image:url(data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAAAEAAAABCAIAAACQd1PeAAAAGXRFWHRTb2Z0d2FyZQBBZG9iZSBJbWFnZVJlYWR5ccllPAAAAA5JREFUeNpiYGBgAAgwAAAEAAGbA+oJAAAAAElFTkSuQmCC) !important}.eg-monroe-element-1{text-shadow:0px 1px 3px rgba(0,0,0,0.1)}.eg-lyndon-johnson-wrapper .esg-entry-cover{background:-moz-radial-gradient(center,ellipse cover,rgba(0,0,0,0.35) 0%,rgba(18,18,18,0) 96%,rgba(19,19,19,0) 100%); background:-webkit-gradient(radial,center center,0px,center center,100%,color-stop(0%,rgba(0,0,0,0.35)),color-stop(96%,rgba(18,18,18,0)),color-stop(100%,rgba(19,19,19,0))); background:-webkit-radial-gradient(center,ellipse cover,rgba(0,0,0,0.35) 0%,rgba(18,18,18,0) 96%,rgba(19,19,19,0) 100%); background:-o-radial-gradient(center,ellipse cover,rgba(0,0,0,0.35) 0%,rgba(18,18,18,0) 96%,rgba(19,19,19,0) 100%); background:-ms-radial-gradient(center,ellipse cover,rgba(0,0,0,0.35) 0%,rgba(18,18,18,0) 96%,rgba(19,19,19,0) 100%); background:radial-gradient(ellipse at center,rgba(0,0,0,0.35) 0%,rgba(18,18,18,0) 96%,rgba(19,19,19,0) 100%); filter:progid:DXImageTransform.Microsoft.gradient( startColorstr='#59000000',endColorstr='#00131313',GradientType=1 )}.eg-wilbert-wrapper .esg-entry-cover{background:-moz-radial-gradient(center,ellipse cover,rgba(0,0,0,0.35) 0%,rgba(18,18,18,0) 96%,rgba(19,19,19,0) 100%); background:-webkit-gradient(radial,center center,0px,center center,100%,color-stop(0%,rgba(0,0,0,0.35)),color-stop(96%,rgba(18,18,18,0)),color-stop(100%,rgba(19,19,19,0))); background:-webkit-radial-gradient(center,ellipse cover,rgba(0,0,0,0.35) 0%,rgba(18,18,18,0) 96%,rgba(19,19,19,0) 100%); background:-o-radial-gradient(center,ellipse cover,rgba(0,0,0,0.35) 0%,rgba(18,18,18,0) 96%,rgba(19,19,19,0) 100%); background:-ms-radial-gradient(center,ellipse cover,rgba(0,0,0,0.35) 0%,rgba(18,18,18,0) 96%,rgba(19,19,19,0) 100%); background:radial-gradient(ellipse at center,rgba(0,0,0,0.35) 0%,rgba(18,18,18,0) 96%,rgba(19,19,19,0) 100%); filter:progid:DXImageTransform.Microsoft.gradient( startColorstr='#59000000',endColorstr='#00131313',GradientType=1 )}.eg-wilbert-wrapper .esg-media-poster{-webkit-transition:0.4s ease-in-out;  -moz-transition:0.4s ease-in-out;  -o-transition:0.4s ease-in-out;  transition:0.4s ease-in-out;  filter:url(\"data:image\/svg+xml;utf8,<svg xmlns='http:\/\/www.w3.org\/2000\/svg'><filter id='grayscale'><feColorMatrix type='matrix' values='0.3333 0.3333 0.3333 0 0 0.3333 0.3333 0.3333 0 0 0.3333 0.3333 0.3333 0 0 0 0 0 1 0'\/><\/filter><\/svg>#grayscale\");   filter:gray;   -webkit-filter:grayscale(100%)}.eg-wilbert-wrapper:hover .esg-media-poster{filter:url(\"data:image\/svg+xml;utf8,<svg xmlns='http:\/\/www.w3.org\/2000\/svg'><filter id='grayscale'><feColorMatrix type='matrix' values='1 0 0 0 0,0 1 0 0 0,0 0 1 0 0,0 0 0 1 0'\/><\/filter><\/svg>#grayscale\");  -webkit-filter:grayscale(0%)}.eg-phillie-element-3:after{content:\" \";width:0px;height:0px;border-style:solid;border-width:5px 5px 0 5px;border-color:#000 transparent transparent transparent;left:50%;margin-left:-5px; bottom:-5px; position:absolute}.eg-howardtaft-wrapper .esg-media-poster{filter:url(\"data:image\/svg+xml;utf8,<svg xmlns='http:\/\/www.w3.org\/2000\/svg'><filter id='grayscale'><feColorMatrix type='matrix' values='1 0 0 0 0,0 1 0 0 0,0 0 1 0 0,0 0 0 1 0'\/><\/filter><\/svg>#grayscale\");  -webkit-filter:grayscale(0%)}.eg-howardtaft-wrapper:hover .esg-media-poster{filter:url(\"data:image\/svg+xml;utf8,<svg xmlns='http:\/\/www.w3.org\/2000\/svg'><filter id='grayscale'><feColorMatrix type='matrix' values='0.3333 0.3333 0.3333 0 0 0.3333 0.3333 0.3333 0 0 0.3333 0.3333 0.3333 0 0 0 0 0 1 0'\/><\/filter><\/svg>#grayscale\");   filter:gray;   -webkit-filter:grayscale(100%)}.myportfolio-container .added_to_cart.wc-forward{font-family:\"Open Sans\"; font-size:13px; color:#fff; margin-top:10px}.esgbox-title.esgbox-title-outside-wrap{font-size:15px; font-weight:700; text-align:center}.esgbox-title.esgbox-title-inside-wrap{padding-bottom:10px; font-size:15px; font-weight:700; text-align:center}a.eg-henryharrison-element-1,a.eg-henryharrison-element-2{-webkit-transition:all .4s linear;   -moz-transition:all .4s linear;   -o-transition:all .4s linear;   -ms-transition:all .4s linear;   transition:all .4s linear}.eg-jimmy-carter-element-11 i:before{margin-left:0px; margin-right:0px}.eg-harding-element-17{letter-spacing:1px}.eg-harding-wrapper .esg-entry-media{overflow:hidden; box-sizing:border-box;   -webkit-box-sizing:border-box;   -moz-box-sizing:border-box;   padding:30px 30px 0px 30px}.eg-harding-wrapper .esg-media-poster{overflow:hidden; border-radius:50%;   -webkit-border-radius:50%;   -moz-border-radius:50%}.eg-ulysses-s-grant-wrapper .esg-entry-media{overflow:hidden; box-sizing:border-box;   -webkit-box-sizing:border-box;   -moz-box-sizing:border-box;   padding:30px 30px 0px 30px}.eg-ulysses-s-grant-wrapper .esg-media-poster{overflow:hidden; border-radius:50%;   -webkit-border-radius:50%;   -moz-border-radius:50%}.eg-richard-nixon-wrapper .esg-entry-media{overflow:hidden; box-sizing:border-box;   -webkit-box-sizing:border-box;   -moz-box-sizing:border-box;   padding:30px 30px 0px 30px}.eg-richard-nixon-wrapper .esg-media-poster{overflow:hidden; border-radius:50%;   -webkit-border-radius:50%;   -moz-border-radius:50%}.eg-herbert-hoover-wrapper .esg-media-poster{filter:url(\"data:image\/svg+xml;utf8,<svg xmlns='http:\/\/www.w3.org\/2000\/svg'><filter id='grayscale'><feColorMatrix type='matrix' values='0.3333 0.3333 0.3333 0 0 0.3333 0.3333 0.3333 0 0 0.3333 0.3333 0.3333 0 0 0 0 0 1 0'\/><\/filter><\/svg>#grayscale\");   filter:gray;   -webkit-filter:grayscale(100%)}.eg-herbert-hoover-wrapper:hover .esg-media-poster{filter:url(\"data:image\/svg+xml;utf8,<svg xmlns='http:\/\/www.w3.org\/2000\/svg'><filter id='grayscale'><feColorMatrix type='matrix' values='1 0 0 0 0,0 1 0 0 0,0 0 1 0 0,0 0 0 1 0'\/><\/filter><\/svg>#grayscale\");  -webkit-filter:grayscale(0%)}.eg-lyndon-johnson-wrapper .esg-media-poster{filter:url(\"data:image\/svg+xml;utf8,<svg xmlns='http:\/\/www.w3.org\/2000\/svg'><filter id='grayscale'><feColorMatrix type='matrix' values='0.3333 0.3333 0.3333 0 0 0.3333 0.3333 0.3333 0 0 0.3333 0.3333 0.3333 0 0 0 0 0 1 0'\/><\/filter><\/svg>#grayscale\");   filter:gray;   -webkit-filter:grayscale(100%)}.eg-lyndon-johnson-wrapper:hover .esg-media-poster{filter:url(\"data:image\/svg+xml;utf8,<svg xmlns='http:\/\/www.w3.org\/2000\/svg'><filter id='grayscale'><feColorMatrix type='matrix' values='1 0 0 0 0,0 1 0 0 0,0 0 1 0 0,0 0 0 1 0'\/><\/filter><\/svg>#grayscale\");  -webkit-filter:grayscale(0%)}.esg-overlay.eg-ronald-reagan-container{background:-moz-linear-gradient(top,rgba(0,0,0,0) 50%,rgba(0,0,0,0.83) 99%,rgba(0,0,0,0.85) 100%); background:-webkit-gradient(linear,left top,left bottom,color-stop(50%,rgba(0,0,0,0)),color-stop(99%,rgba(0,0,0,0.83)),color-stop(100%,rgba(0,0,0,0.85))); background:-webkit-linear-gradient(top,rgba(0,0,0,0) 50%,rgba(0,0,0,0.83) 99%,rgba(0,0,0,0.85) 100%); background:-o-linear-gradient(top,rgba(0,0,0,0) 50%,rgba(0,0,0,0.83) 99%,rgba(0,0,0,0.85) 100%); background:-ms-linear-gradient(top,rgba(0,0,0,0) 50%,rgba(0,0,0,0.83) 99%,rgba(0,0,0,0.85) 100%); background:linear-gradient(to bottom,rgba(0,0,0,0) 50%,rgba(0,0,0,0.83) 99%,rgba(0,0,0,0.85) 100%); filter:progid:DXImageTransform.Microsoft.gradient( startColorstr='#00000000',endColorstr='#d9000000',GradientType=0 )}.eg-georgebush-wrapper .esg-entry-cover{background:-moz-linear-gradient(top,rgba(0,0,0,0) 50%,rgba(0,0,0,0.83) 99%,rgba(0,0,0,0.85) 100%); background:-webkit-gradient(linear,left top,left bottom,color-stop(50%,rgba(0,0,0,0)),color-stop(99%,rgba(0,0,0,0.83)),color-stop(100%,rgba(0,0,0,0.85))); background:-webkit-linear-gradient(top,rgba(0,0,0,0) 50%,rgba(0,0,0,0.83) 99%,rgba(0,0,0,0.85) 100%); background:-o-linear-gradient(top,rgba(0,0,0,0) 50%,rgba(0,0,0,0.83) 99%,rgba(0,0,0,0.85) 100%); background:-ms-linear-gradient(top,rgba(0,0,0,0) 50%,rgba(0,0,0,0.83) 99%,rgba(0,0,0,0.85) 100%); background:linear-gradient(to bottom,rgba(0,0,0,0) 50%,rgba(0,0,0,0.83) 99%,rgba(0,0,0,0.85) 100%); filter:progid:DXImageTransform.Microsoft.gradient( startColorstr='#00000000',endColorstr='#d9000000',GradientType=0 )}.eg-jefferson-wrapper{-webkit-border-radius:5px !important; -moz-border-radius:5px !important; border-radius:5px !important; -webkit-mask-image:url(data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAAAEAAAABCAIAAACQd1PeAAAAGXRFWHRTb2Z0d2FyZQBBZG9iZSBJbWFnZVJlYWR5ccllPAAAAA5JREFUeNpiYGBgAAgwAAAEAAGbA+oJAAAAAElFTkSuQmCC) !important}.eg-monroe-element-1{text-shadow:0px 1px 3px rgba(0,0,0,0.1)}.eg-lyndon-johnson-wrapper .esg-entry-cover{background:-moz-radial-gradient(center,ellipse cover,rgba(0,0,0,0.35) 0%,rgba(18,18,18,0) 96%,rgba(19,19,19,0) 100%); background:-webkit-gradient(radial,center center,0px,center center,100%,color-stop(0%,rgba(0,0,0,0.35)),color-stop(96%,rgba(18,18,18,0)),color-stop(100%,rgba(19,19,19,0))); background:-webkit-radial-gradient(center,ellipse cover,rgba(0,0,0,0.35) 0%,rgba(18,18,18,0) 96%,rgba(19,19,19,0) 100%); background:-o-radial-gradient(center,ellipse cover,rgba(0,0,0,0.35) 0%,rgba(18,18,18,0) 96%,rgba(19,19,19,0) 100%); background:-ms-radial-gradient(center,ellipse cover,rgba(0,0,0,0.35) 0%,rgba(18,18,18,0) 96%,rgba(19,19,19,0) 100%); background:radial-gradient(ellipse at center,rgba(0,0,0,0.35) 0%,rgba(18,18,18,0) 96%,rgba(19,19,19,0) 100%); filter:progid:DXImageTransform.Microsoft.gradient( startColorstr='#59000000',endColorstr='#00131313',GradientType=1 )}.eg-wilbert-wrapper .esg-entry-cover{background:-moz-radial-gradient(center,ellipse cover,rgba(0,0,0,0.35) 0%,rgba(18,18,18,0) 96%,rgba(19,19,19,0) 100%); background:-webkit-gradient(radial,center center,0px,center center,100%,color-stop(0%,rgba(0,0,0,0.35)),color-stop(96%,rgba(18,18,18,0)),color-stop(100%,rgba(19,19,19,0))); background:-webkit-radial-gradient(center,ellipse cover,rgba(0,0,0,0.35) 0%,rgba(18,18,18,0) 96%,rgba(19,19,19,0) 100%); background:-o-radial-gradient(center,ellipse cover,rgba(0,0,0,0.35) 0%,rgba(18,18,18,0) 96%,rgba(19,19,19,0) 100%); background:-ms-radial-gradient(center,ellipse cover,rgba(0,0,0,0.35) 0%,rgba(18,18,18,0) 96%,rgba(19,19,19,0) 100%); background:radial-gradient(ellipse at center,rgba(0,0,0,0.35) 0%,rgba(18,18,18,0) 96%,rgba(19,19,19,0) 100%); filter:progid:DXImageTransform.Microsoft.gradient( startColorstr='#59000000',endColorstr='#00131313',GradientType=1 )}.eg-wilbert-wrapper .esg-media-poster{-webkit-transition:0.4s ease-in-out;  -moz-transition:0.4s ease-in-out;  -o-transition:0.4s ease-in-out;  transition:0.4s ease-in-out;  filter:url(\"data:image\/svg+xml;utf8,<svg xmlns='http:\/\/www.w3.org\/2000\/svg'><filter id='grayscale'><feColorMatrix type='matrix' values='0.3333 0.3333 0.3333 0 0 0.3333 0.3333 0.3333 0 0 0.3333 0.3333 0.3333 0 0 0 0 0 1 0'\/><\/filter><\/svg>#grayscale\");   filter:gray;   -webkit-filter:grayscale(100%)}.eg-wilbert-wrapper:hover .esg-media-poster{filter:url(\"data:image\/svg+xml;utf8,<svg xmlns='http:\/\/www.w3.org\/2000\/svg'><filter id='grayscale'><feColorMatrix type='matrix' values='1 0 0 0 0,0 1 0 0 0,0 0 1 0 0,0 0 0 1 0'\/><\/filter><\/svg>#grayscale\");  -webkit-filter:grayscale(0%)}.eg-phillie-element-3:after{content:\" \";width:0px;height:0px;border-style:solid;border-width:5px 5px 0 5px;border-color:#000 transparent transparent transparent;left:50%;margin-left:-5px; bottom:-5px; position:absolute}.eg-howardtaft-wrapper .esg-media-poster,.eg-howardtaft-wrapper .esg-media-poster{filter:url(\"data:image\/svg+xml;utf8,<svg xmlns='http:\/\/www.w3.org\/2000\/svg'><filter id='grayscale'><feColorMatrix type='matrix' values='1 0 0 0 0,0 1 0 0 0,0 0 1 0 0,0 0 0 1 0'\/><\/filter><\/svg>#grayscale\");  -webkit-filter:grayscale(0%)}.eg-howardtaft-wrapper:hover .esg-media-poster,.eg-howardtaft-wrapper:hover .esg-media-poster{filter:url(\"data:image\/svg+xml;utf8,<svg xmlns='http:\/\/www.w3.org\/2000\/svg'><filter id='grayscale'><feColorMatrix type='matrix' values='0.3333 0.3333 0.3333 0 0 0.3333 0.3333 0.3333 0 0 0.3333 0.3333 0.3333 0 0 0 0 0 1 0'\/><\/filter><\/svg>#grayscale\");   filter:gray;   -webkit-filter:grayscale(100%)}.myportfolio-container .added_to_cart.wc-forward{font-family:\"Open Sans\"; font-size:13px; color:#fff; margin-top:10px}.esgbox-title.esgbox-title-outside-wrap{font-size:15px; font-weight:700; text-align:center}.esgbox-title.esgbox-title-inside-wrap{padding-bottom:10px; font-size:15px; font-weight:700; text-align:center}.esg-content.eg-twitterstream-element-33-a{display:inline-block}.eg-twitterstream-element-35{word-break:break-all}.esg-overlay.eg-twitterstream-container{background:-moz-linear-gradient(top,rgba(0,0,0,0) 50%,rgba(0,0,0,0.83) 99%,rgba(0,0,0,0.85) 100%); background:-webkit-gradient(linear,left top,left bottom,color-stop(50%,rgba(0,0,0,0)),color-stop(99%,rgba(0,0,0,0.83)),color-stop(100%,rgba(0,0,0,0.85))); background:-webkit-linear-gradient(top,rgba(0,0,0,0) 50%,rgba(0,0,0,0.83) 99%,rgba(0,0,0,0.85) 100%); background:-o-linear-gradient(top,rgba(0,0,0,0) 50%,rgba(0,0,0,0.83) 99%,rgba(0,0,0,0.85) 100%); background:-ms-linear-gradient(top,rgba(0,0,0,0) 50%,rgba(0,0,0,0.83) 99%,rgba(0,0,0,0.85) 100%); background:linear-gradient(to bottom,rgba(0,0,0,0) 50%,rgba(0,0,0,0.83) 99%,rgba(0,0,0,0.85) 100%); filter:progid:DXImageTransform.Microsoft.gradient( startColorstr='#00000000',endColorstr='#d9000000',GradientType=0 )}.esg-content.eg-facebookstream-element-33-a{display:inline-block}.eg-facebookstream-element-0{word-break:break-all}.esg-overlay.eg-flickrstream-container{background:-moz-linear-gradient(top,rgba(0,0,0,0) 50%,rgba(0,0,0,0.83) 99%,rgba(0,0,0,0.85) 100%); background:-webkit-gradient(linear,left top,left bottom,color-stop(50%,rgba(0,0,0,0)),color-stop(99%,rgba(0,0,0,0.83)),color-stop(100%,rgba(0,0,0,0.85))); background:-webkit-linear-gradient(top,rgba(0,0,0,0) 50%,rgba(0,0,0,0.83) 99%,rgba(0,0,0,0.85) 100%); background:-o-linear-gradient(top,rgba(0,0,0,0) 50%,rgba(0,0,0,0.83) 99%,rgba(0,0,0,0.85) 100%); background:-ms-linear-gradient(top,rgba(0,0,0,0) 50%,rgba(0,0,0,0.83) 99%,rgba(0,0,0,0.85) 100%); background:linear-gradient(to bottom,rgba(0,0,0,0) 50%,rgba(0,0,0,0.83) 99%,rgba(0,0,0,0.85) 100%); filter:progid:DXImageTransform.Microsoft.gradient( startColorstr='#00000000',endColorstr='#d9000000',GradientType=0 )}<\/style>\n<style type=\"text\/css\">.minimal-light .navigationbuttons,.minimal-light .esg-pagination,.minimal-light .esg-filters{text-align:center}.minimal-light .esg-filter-wrapper.dropdownstyle >.esg-selected-filterbutton,.minimal-light input.eg-search-input,.minimal-light .esg-filterbutton,.minimal-light .esg-navigationbutton,.minimal-light .esg-sortbutton,.minimal-light .esg-cartbutton a,.minimal-light .esg-filter-wrapper.eg-search-wrapper .eg-search-clean,.minimal-light .esg-filter-wrapper.eg-search-wrapper .eg-search-submit{color:#999; margin-right:5px; cursor:pointer; padding:0px 16px; border:1px solid #e5e5e5; line-height:38px; border-radius:5px; font-size:12px; font-weight:700; font-family:\"Open Sans\",sans-serif; display:inline-block; background:#fff; margin-bottom:5px; white-space:nowrap; min-height:38px; vertical-align:middle}.minimal-light input.eg-search-input::placeholder{line-height:38px; vertical-align:middle}.minimal-light .esg-navigationbutton *{color:#999}.minimal-light .esg-navigationbutton{padding:0px 16px}.minimal-light .esg-pagination-button:last-child{margin-right:0}.minimal-light .esg-left,.minimal-light .esg-right{padding:0px 11px}.minimal-light .esg-sortbutton-wrapper,.minimal-light .esg-cartbutton-wrapper{display:inline-block}.minimal-light .esg-sortbutton-order,.minimal-light .esg-cartbutton-order{display:inline-block; vertical-align:top; border:1px solid #e5e5e5; width:40px; line-height:38px; border-radius:0px 5px 5px 0px; font-size:12px; font-weight:700; color:#999; cursor:pointer; background:#fff}.minimal-light .esg-cartbutton{color:#333; cursor:default !important}.minimal-light .esg-cartbutton .esgicon-basket{color:#333; font-size:15px; line-height:15px; margin-right:10px}.minimal-light .esg-cartbutton-wrapper{cursor:default !important}.minimal-light .esg-sortbutton,.minimal-light .esg-cartbutton{display:inline-block; position:relative; cursor:pointer; margin-right:0px; border-right:none; border-radius:5px 0px 0px 5px}.minimal-light input.eg-search-input.hovered,.minimal-light input.eg-search-input:focus,.minimal-light .esg-navigationbutton.hovered,.minimal-light .esg-filterbutton.hovered,.minimal-light .esg-sortbutton.hovered,.minimal-light .esg-sortbutton-order.hovered,.minimal-light .esg-cartbutton.hovered a,.minimal-light .esg-filter-wrapper.dropdownstyle >.esg-selected-filterbutton.hovered,.minimal-light .esg-filterbutton.selected,.minimal-light .esg-filter-wrapper.eg-search-wrapper .eg-search-clean.hovered,.minimal-light .esg-filter-wrapper.eg-search-wrapper .eg-search-submit.hovered{background-color:#fff; border-color:#bbb; color:#333; box-shadow:0px 3px 5px 0px rgba(0,0,0,0.13)}.minimal-light .esg-navigationbutton.hovered *{color:#333}.minimal-light .esg-sortbutton-order.hovered .tp-desc{border-color:#bbb; color:#333; box-shadow:0px -3px 5px 0px rgba(0,0,0,0.13) !important}.minimal-light .esg-filter-checked{color:#cbcbcb; background:#cbcbcb; margin-left:10px; font-size:9px; font-weight:300; line-height:9px; vertical-align:middle}.minimal-light .esg-filter-wrapper.dropdownstyle .esg-filter-checked{margin-left:-22px; margin-right:10px}.minimal-light .esg-filterbutton.selected .esg-filter-checked,.minimal-light .esg-filterbutton.hovered .esg-filter-checked{color:#fff; background:#000}.minimal-light .esg-filter-wrapper.eg-search-wrapper{white-space:nowrap}.minimal-light .esg-filter-wrapper.eg-search-wrapper .eg-search-clean,.minimal-light .esg-filter-wrapper.eg-search-wrapper .eg-search-submit{width:40px; padding:0px; margin-left:5px; margin-right:0px}.minimal-light .esg-filter-wrapper.eg-search-wrapper .eg-search-input{width:auto}.minimal-light .esg-dropdown-wrapper{transform:translateZ(10px) translateX(-50%); left:50%; background:rgba(255,255,255,0.95); border-radius:5px; border:1px solid #e5e5e5}.minimal-light .esg-dropdown-wrapper .esg-filterbutton{position:relative; border:none; box-shadow:none; text-align:left; color:#999; background:transparent; line-height:25px; min-height:25px}.minimal-light .esg-dropdown-wrapper .esg-filterbutton.hovered,.minimal-light .esg-dropdown-wrapper .esg-filterbutton.selected{color:#333}.minimal-light .esg-selected-filterbutton .eg-icon-down-open{margin-right:-10px; font-size:12px}.minimal-light .esg-selected-filterbutton.hovered .eg-icon-down-open{color:#333}<\/style>\n<style type=\"text\/css\">.eg-emily-element-1{font-size:16px !important; line-height:22px !important; color:#ffffff !important; font-weight:400 !important; padding:17px 17px 17px 17px !important; border-radius:0px 0px 0px 0px !important; background:#fba681 !important; z-index:2 !important; display:block; border-top-width:0px !important; border-right-width:0px !important; border-bottom-width:0px !important; border-left-width:0px !important; border-color:#ffffff !important; border-style:solid !important}<\/style>\n<style type=\"text\/css\">.eg-emily-element-1:hover{font-size:16px !important; line-height:22px !important; color:#ffffff !important; font-weight:400 !important; border-radius:0px 0px 0px 0px !important; background:#e5936f !important; border-top-width:0px !important; border-right-width:0px !important; border-bottom-width:0px !important; border-left-width:0px !important; border-color:#ffffff !important; border-style:solid !important}<\/style>\n<style type=\"text\/css\">.eg-emily-element-1-a{display:inline-block !important; float:none !important; clear:none !important; margin:0px 0px 0px 0px !important; position:relative !important}<\/style>\n<style type=\"text\/css\">.eg-emily-container{background:rgba(54,56,57,0.25)}<\/style>\n<style type=\"text\/css\">.eg-emily-content{background:#ffffff; padding:0px 0px 0px 0px; border-width:0px 0px 0px 0px; border-radius:0px 0px 0px 0px; border-color:transparent; border-style:none; text-align:left}<\/style>\n<style type=\"text\/css\">.esg-grid .mainul li.eg-emily-wrapper{background:#ffffff; padding:0px 0px 0px 0px; border-width:0px 0px 0px 0px; border-radius:0px 0px 0px 0px; border-color:transparent; border-style:none}<\/style>\n<style type=\"text\/css\">.esg-grid .mainul li.eg-emily-wrapper .esg-media-poster{background-size:cover; background-position:center center; background-repeat:no-repeat}<\/style>\n<!-- THE ESSENTIAL GRID 3.0.16 POST -->\n\n<article class=\"myportfolio-container minimal-light esg-entry-skin-emily source_type_post\" id=\"esg-grid-5-1-wrap\">\n\n   <div id=\"esg-grid-5-1\" class=\"esg-grid\" style=\"background: #ffffff;padding: 0px 0px 0px 0px ; box-sizing:border-box; -moz-box-sizing:border-box; -webkit-box-sizing:border-box; display:none\">\n<ul>\n<li id=\"eg-5-post-id-257_117\" data-skin=\"emily\" class=\"filterall filter-ideal-look eg-emily-wrapper eg-post-id-257\" data-date=\"1500544901\" data-cobblesw=\"2\" data-cobblesh=\"1\">\n    <div class=\"esg-media-cover-wrapper\">\n<div class=\"esg-entry-media\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/softfardamentos.com.br\/wp-content\/uploads\/2017\/07\/IMG_3688.jpg\" data-no-lazy=\"1\" alt=\"\" width=\"600\" height=\"800\"><\/div>\n\n            <div class=\"esg-entry-cover\">\n\n                <div class=\"esg-overlay esg-transition eg-emily-container\" data-delay=\"0\" data-duration=\"default\" data-transition=\"esg-fade\"><\/div>\n\n\t\t\t\t<div class=\"esg-center eg-post-257 eg-emily-element-1-a esg-transition\" data-delay=\"0.1\" data-duration=\"default\" data-transition=\"esg-slide\"><a class=\"eg-emily-element-1 eg-post-257 esgbox\" data-thumb=\"https:\/\/softfardamentos.com.br\/wp-content\/uploads\/2017\/07\/IMG_3688.jpg\" href=\"https:\/\/softfardamentos.com.br\/wp-content\/uploads\/2017\/07\/IMG_3688.jpg\" data-width=\"600\"  data-height=\"800\" ><i class=\"eg-icon-search\"><\/i><\/a><\/div>\n           <\/div>\n   <\/div>\n\n<\/li>\n<li id=\"eg-5-post-id-264_2023\" data-skin=\"emily\" class=\"filterall filter-ideal-look eg-emily-wrapper eg-post-id-264\" data-date=\"1500545634\" data-cobblesw=\"1\" data-cobblesh=\"1\">\n    <div class=\"esg-media-cover-wrapper\">\n<div class=\"esg-entry-media\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/softfardamentos.com.br\/wp-content\/uploads\/2017\/07\/IMG_3705.jpg\" data-no-lazy=\"1\" alt=\"\" width=\"600\" height=\"1068\"><\/div>\n\n            <div class=\"esg-entry-cover\">\n\n                <div class=\"esg-overlay esg-transition eg-emily-container\" data-delay=\"0\" data-duration=\"default\" data-transition=\"esg-fade\"><\/div>\n\n\t\t\t\t<div class=\"esg-center eg-post-264 eg-emily-element-1-a esg-transition\" data-delay=\"0.1\" data-duration=\"default\" data-transition=\"esg-slide\"><a class=\"eg-emily-element-1 eg-post-264 esgbox\" data-thumb=\"https:\/\/softfardamentos.com.br\/wp-content\/uploads\/2017\/07\/IMG_3705.jpg\" href=\"https:\/\/softfardamentos.com.br\/wp-content\/uploads\/2017\/07\/IMG_3705.jpg\" data-width=\"600\"  data-height=\"1068\" ><i class=\"eg-icon-search\"><\/i><\/a><\/div>\n           <\/div>\n   <\/div>\n\n<\/li>\n<li id=\"eg-5-post-id-265_4305\" data-skin=\"emily\" class=\"filterall filter-ideal-look eg-emily-wrapper eg-post-id-265\" data-date=\"1500545674\" data-cobblesw=\"1\" data-cobblesh=\"1\">\n    <div class=\"esg-media-cover-wrapper\">\n<div class=\"esg-entry-media\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/softfardamentos.com.br\/wp-content\/uploads\/2017\/07\/1-Capacete.jpg\" data-no-lazy=\"1\" alt=\"\" width=\"700\" height=\"464\"><\/div>\n\n            <div class=\"esg-entry-cover\">\n\n                <div class=\"esg-overlay esg-transition eg-emily-container\" data-delay=\"0\" data-duration=\"default\" data-transition=\"esg-fade\"><\/div>\n\n\t\t\t\t<div class=\"esg-center eg-post-265 eg-emily-element-1-a esg-transition\" data-delay=\"0.1\" data-duration=\"default\" data-transition=\"esg-slide\"><a class=\"eg-emily-element-1 eg-post-265 esgbox\" data-thumb=\"https:\/\/softfardamentos.com.br\/wp-content\/uploads\/2017\/07\/1-Capacete.jpg\" href=\"https:\/\/softfardamentos.com.br\/wp-content\/uploads\/2017\/07\/1-Capacete.jpg\" data-width=\"700\"  data-height=\"464\" ><i class=\"eg-icon-search\"><\/i><\/a><\/div>\n           <\/div>\n   <\/div>\n\n<\/li>\n<li id=\"eg-5-post-id-266_5008\" data-skin=\"emily\" class=\"filterall filter-ideal-look eg-emily-wrapper eg-post-id-266\" data-date=\"1500545701\" data-cobblesw=\"2\" data-cobblesh=\"1\">\n    <div class=\"esg-media-cover-wrapper\">\n<div class=\"esg-entry-media\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/softfardamentos.com.br\/wp-content\/uploads\/2017\/07\/IMG_3708.jpg\" data-no-lazy=\"1\" alt=\"\" width=\"600\" height=\"1068\"><\/div>\n\n            <div class=\"esg-entry-cover\">\n\n                <div class=\"esg-overlay esg-transition eg-emily-container\" data-delay=\"0\" data-duration=\"default\" data-transition=\"esg-fade\"><\/div>\n\n\t\t\t\t<div class=\"esg-center eg-post-266 eg-emily-element-1-a esg-transition\" data-delay=\"0.1\" data-duration=\"default\" data-transition=\"esg-slide\"><a class=\"eg-emily-element-1 eg-post-266 esgbox\" data-thumb=\"https:\/\/softfardamentos.com.br\/wp-content\/uploads\/2017\/07\/IMG_3708.jpg\" href=\"https:\/\/softfardamentos.com.br\/wp-content\/uploads\/2017\/07\/IMG_3708.jpg\" data-width=\"600\"  data-height=\"1068\" ><i class=\"eg-icon-search\"><\/i><\/a><\/div>\n           <\/div>\n   <\/div>\n\n<\/li>\n<li id=\"eg-5-post-id-267_8023\" data-skin=\"emily\" class=\"filterall filter-ideal-look eg-emily-wrapper eg-post-id-267\" data-date=\"1500545726\" data-cobblesw=\"2\" data-cobblesh=\"2\">\n    <div class=\"esg-media-cover-wrapper\">\n<div class=\"esg-entry-media\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/softfardamentos.com.br\/wp-content\/uploads\/2017\/07\/IMG_3706.jpg\" data-no-lazy=\"1\" alt=\"\" width=\"600\" height=\"1068\"><\/div>\n\n            <div class=\"esg-entry-cover\">\n\n                <div class=\"esg-overlay esg-transition eg-emily-container\" data-delay=\"0\" data-duration=\"default\" data-transition=\"esg-fade\"><\/div>\n\n\t\t\t\t<div class=\"esg-center eg-post-267 eg-emily-element-1-a esg-transition\" data-delay=\"0.1\" data-duration=\"default\" data-transition=\"esg-slide\"><a class=\"eg-emily-element-1 eg-post-267 esgbox\" data-thumb=\"https:\/\/softfardamentos.com.br\/wp-content\/uploads\/2017\/07\/IMG_3706.jpg\" href=\"https:\/\/softfardamentos.com.br\/wp-content\/uploads\/2017\/07\/IMG_3706.jpg\" data-width=\"600\"  data-height=\"1068\" ><i class=\"eg-icon-search\"><\/i><\/a><\/div>\n           <\/div>\n   <\/div>\n\n<\/li>\n<li id=\"eg-5-post-id-268_9389\" data-skin=\"emily\" class=\"filterall filter-ideal-look eg-emily-wrapper eg-post-id-268\" data-date=\"1500545752\" data-cobblesw=\"2\" data-cobblesh=\"1\">\n    <div class=\"esg-media-cover-wrapper\">\n<div class=\"esg-entry-media\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/softfardamentos.com.br\/wp-content\/uploads\/2017\/07\/2-luva.jpg\" data-no-lazy=\"1\" alt=\"\" width=\"550\" height=\"550\"><\/div>\n\n            <div class=\"esg-entry-cover\">\n\n                <div class=\"esg-overlay esg-transition eg-emily-container\" data-delay=\"0\" data-duration=\"default\" data-transition=\"esg-fade\"><\/div>\n\n\t\t\t\t<div class=\"esg-center eg-post-268 eg-emily-element-1-a esg-transition\" data-delay=\"0.1\" data-duration=\"default\" data-transition=\"esg-slide\"><a class=\"eg-emily-element-1 eg-post-268 esgbox\" data-thumb=\"https:\/\/softfardamentos.com.br\/wp-content\/uploads\/2017\/07\/2-luva.jpg\" href=\"https:\/\/softfardamentos.com.br\/wp-content\/uploads\/2017\/07\/2-luva.jpg\" data-width=\"550\"  data-height=\"550\" ><i class=\"eg-icon-search\"><\/i><\/a><\/div>\n           <\/div>\n   <\/div>\n\n<\/li>\n<\/ul>\n    <\/div>\n\n<\/article>\n<div class=\"clear\"><\/div>\n<script type=\"text\/javascript\">\nvar essapi_5_1;\nfunction esginit_5_1() {\njQuery(document).ready(function() {\n  var lightboxOptions = {\n        margin : [0,0,0,0],\n        buttons : [\"share\",\"thumbs\",\"close\"],\n        infobar : true,\n        loop : true,\n        slideShow : {\"autoStart\": false, \"speed\": 3000},\n        videoAutoPlay : true,\n        animationEffect : \"fade\",\n        animationDuration : 500,\n        beforeShow: function(a, c) {\n          var i = 0,\n              multiple = false;\n          a = a.slides;\n          for(var b in a) {\n            i++;\n            if (i > 1) {\n              multiple = true;\n              break;\n            }\n          }\n          if (!multiple) jQuery(\"body\").addClass(\"esgbox-single\");\n          if (c.type === \"image\") jQuery(\".esgbox-button--zoom\").show();\n          if (c.contentType === \"html\") c.$slide.addClass(\"esgbox-slide--overflow-\" + c.opts.overflow);\n        },\n        beforeLoad: function(a, b) {\n          jQuery(\"body\").removeClass(\"esg-four-by-three\");\n          if (b.opts.$orig.data(\"ratio\") === \"4:3\") jQuery(\"body\").addClass(\"esg-four-by-three\");\n        },\n        afterLoad: function() {jQuery(window).trigger(\"resize.esglb\");},\n        afterClose : function() {jQuery(\"body\").removeClass(\"esgbox-hidearrows esgbox-single\");},\n        transitionEffect : \"fade\",\n        transitionDuration : 500,\n        hash : \"group\",\n        arrows : true,\n        wheel : false,\n        baseClass : \"esgbox-container-5\",\n        captionPosition : \"bottom\",\n        overflow : \"auto\",\n  };\n\n  jQuery(\"#esg-grid-5-1\").data(\"lightboxsettings\", lightboxOptions);\n\n  essapi_5_1 = jQuery(\"#esg-grid-5-1\").tpessential({\n        gridID:5,\n        layout:\"cobbles\",\n        lazyLoad:\"off\",\n        row:3,\n        apiName: \"essapi_5_1\",\n        loadMoreAjaxToken:\"b418adcc74\",\n        loadMoreAjaxUrl:\"https:\/\/softfardamentos.com.br\/wp-admin\/admin-ajax.php\",\n        loadMoreAjaxAction:\"Essential_Grid_Front_request_ajax\",\n        ajaxContentTarget:\"ess-grid-ajax-container-\",\n        ajaxScrollToOffset:\"0\",\n        ajaxCloseButton:\"off\",\n        ajaxContentSliding:\"on\",\n        ajaxScrollToOnLoad:\"on\",\n        ajaxCallbackArgument:\"off\",\n        ajaxNavButton:\"off\",\n        ajaxCloseType:\"type1\",\n        ajaxCloseInner:\"false\",\n        ajaxCloseStyle:\"light\",\n        ajaxClosePosition:\"tr\",\n        space:8,\n        pageAnimation:\"fade\",\n        videoPlaybackInGrid: \"on\",\n        videoLoopInGrid: \"on\",\n        videoPlaybackOnHover: \"off\",\n        videoInlineMute: \"on\",\n        videoInlineControls: \"off\",\n        keepLayersInline: \"off\",\n        startAnimation: \"none\",\n        startAnimationSpeed: 1000,\n        startAnimationDelay: 100,\n        startAnimationType: \"item\",\n        animationType: \"item\",\n        paginationScrollToTop:\"off\",\n        paginationAutoplay:\"off\",\n        spinner:\"spinner0\",\n        minVisibleItems:3,\n        lightBoxMode:\"all\",\n        lightboxHash:\"group\",\n        lightboxPostMinWid:\"75%\",\n        lightboxPostMaxWid:\"75%\",\n        lightboxSpinner:\"off\",\n        lightBoxFeaturedImg:\"off\",\n        lightBoxPostTitle:\"off\",\n        lightBoxPostTitleTag:\"h2\",\n        lightboxMargin : \"0|0|0|0\",\n        lbContentPadding : \"0|0|0|0\",\n        lbContentOverflow : \"auto\",\n        cobblesPattern:\"2x1,2x2,2x1,1x1,1x1,2x1\",\n        animSpeed:1000,\n        delayBasic:1,\n        mainhoverdelay:1,\n        filterType:\"single\",\n        showDropFilter:\"hover\",\n        filterGroupClass:\"esg-fgc-5\",\n        filterNoMatch:\"No Items for the Selected Filter\",\n        filterDeepLink:\"off\",\n        hideMarkups: \"on\",\n        inViewport: true,\n        viewportBuffer: 20,\n        youtubeNoCookie:\"false\",\n        convertFilterMobile:false,\n        convertFilterMobileWidth:768,\n        paginationSwipe: \"off\",\n        paginationDragVer: \"on\",\n        pageSwipeThrottle: 30,\n        aspectratio:\"209:296\",\n        hideBlankItemsAt: \"1\",\n        responsiveEntries: [\n            { width:1900,amount:6,mmheight:0},\n            { width:1400,amount:6,mmheight:0},\n            { width:1170,amount:6,mmheight:0},\n            { width:1024,amount:6,mmheight:0},\n            { width:960,amount:6,mmheight:0},\n            { width:778,amount:6,mmheight:0},\n            { width:640,amount:6,mmheight:0},\n            { width:480,amount:1,mmheight:0},\n            ]\n  });\n\n\n});\n} \/\/ End of EsgInitScript\nvar once_5_1 = false;\nif (document.readyState === \"loading\") document.addEventListener('readystatechange',function() { if ((document.readyState === \"interactive\" || document.readyState === \"complete\") && !once_5_1 ) { once_5_1 = true; esginit_5_1();}}); else {once_5_1 = true; esginit_5_1();}\n<\/script>\n[vc_empty_space alter_height=\"huge\" hide_on_desktop=\"\" hide_on_notebook=\"\" hide_on_tablet=\"\" hide_on_mobile=\"\" css=\".vc_custom_1507301052429{margin-top: -0.8rem !important;}\"][\/vc_column][\/vc_row]<\/div>[vc_empty_space alter_height=&#8221;huge&#8221; hide_on_desktop=&#8221;&#8221; hide_on_notebook=&#8221;&#8221; hide_on_tablet=&#8221;&#8221; hide_on_mobile=&#8221;&#8221;][\/vc_column][\/vc_row][vc_row content_placement=&#8221;middle&#8221; hide_bg_image_on_tablet=&#8221;&#8221; hide_bg_image_on_mobile=&#8221;&#8221;][vc_column hide_bg_image_on_tablet=&#8221;&#8221; hide_bg_image_on_mobile=&#8221;&#8221;]<div class=\"sc_layouts sc_layouts_default sc_layouts_688\">[vc_row full_width=\"stretch_row_content_no_spaces\" content_placement=\"middle\" hide_bg_image_on_tablet=\"\" hide_bg_image_on_mobile=\"\" css=\".vc_custom_1507629280097{background-color: #f6eee2 !important;background-size: cover !important;}\"][vc_column width=\"1\/12\" icons_position=\"left\" offset=\"vc_hidden-md vc_hidden-sm vc_hidden-xs\"]<div id=\"slider_controller_520721584\" class=\"sc_slider_controller sc_slider_controller_thumbs sc_slider_controller_vertical sc_slider_controller_height_fixed\" data-slider-id=\"home_slider\" data-style=\"thumbs\" data-controls=\"0\" data-interval=\"7000\" data-effect=\"slide\" data-direction=\"vertical\" data-slides-per-view=\"3\" data-slides-space=\"8\" data-height=\"270px\"><\/div>[\/vc_column][vc_column width=\"5\/12\" icons_position=\"left\" offset=\"vc_col-lg-offset-0 vc_col-sm-offset-1 vc_col-xs-offset-1 vc_col-xs-10\"][vc_empty_space alter_height=\"medium\" hide_on_desktop=\"1\" hide_on_notebook=\"1\" hide_on_tablet=\"1\" hide_on_mobile=\"\"]<div id=\"home_slider\" class=\"widget_area sc_widget_slider vc_widget_slider wpb_content_element\"><aside id=\"home_slider_widget\" class=\"widget widget_slider\">\t\t\t<div class=\"slider_wrap slider_engine_swiper\">\n\t\t\t\t<div id=\"home_slider_outer\" class=\"slider_outer slider_swiper_outer slider_style_default slider_outer_direction_horizontal slider_outer_one slider_outer_nopagination slider_outer_nocontrols slider_outer_titles_center\"><div id=\"home_slider_swiper\" class=\"slider_container slider_swiper swiper-slider-container slider_nocontrols slider_titles_center slider_resize slider_height_auto slider_direction_horizontal slider_nopagination slider_one slider_type_bg\" data-ratio=\"1:1\" data-interval=\"7000\" data-effect=\"slide\" data-pagination=\"bullets\" data-direction=\"horizontal\" data-slides-per-view=\"1\" data-slides-space=\"0\"><div class=\"slider-wrapper swiper-wrapper\"><div  class=\"slider-slide swiper-slide\" data-image=\"https:\/\/softfardamentos.com.br\/wp-content\/uploads\/2017\/10\/fotos_duo_besc_m.png\" style=\"background-image:url(https:\/\/softfardamentos.com.br\/wp-content\/uploads\/2017\/10\/fotos_duo_besc_m.png);\"><\/div><div  class=\"slider-slide swiper-slide\" data-image=\"https:\/\/softfardamentos.com.br\/wp-content\/uploads\/2017\/10\/fotos_duo_besc_m.png\" style=\"background-image:url(https:\/\/softfardamentos.com.br\/wp-content\/uploads\/2017\/10\/fotos_duo_besc_m.png);\"><\/div><\/div><!-- \/.slider-wrapper --><\/div><!-- \/.slider_container --><\/div><!-- \/.slider_outer -->\t\t\t<\/div>\n\t\t\t<\/aside><\/div>[\/vc_column][vc_column width=\"1\/2\" icons_position=\"left\" offset=\"vc_col-sm-offset-0 vc_col-xs-offset-1 vc_col-xs-10\"][vc_empty_space alter_height=\"medium\" hide_on_desktop=\"1\" hide_on_notebook=\"1\" hide_on_tablet=\"1\" hide_on_mobile=\"\"]<div id=\"sc_content_317422457\"\n\t\tclass=\"sc_content color_style_default sc_content_default sc_content_width_1_2 sc_float_left\"><div class=\"sc_content_container\">[vc_row_inner][vc_column_inner icons_position=\"left\" offset=\"vc_col-md-offset-2 vc_col-md-10 vc_col-sm-offset-0\"]<div id=\"sc_title_644823161\"\n\t\tclass=\"sc_title color_style_default sc_title_default\"><h3 class=\"sc_item_title sc_title_title sc_align_left sc_item_title_style_default\">Depoimentos de clientes<\/h3><div class=\"sc_item_descr sc_title_descr sc_align_left\"><p>Confira o depoimento de alguns dos nossos clientes, que compraram conosco e ficaram satisfeitos com nosso trabalho!<\/p>\n<\/div><\/div><!-- \/.sc_title -->[vc_empty_space alter_height=\"small\" hide_on_desktop=\"\" hide_on_notebook=\"1\" hide_on_tablet=\"1\" hide_on_mobile=\"1\" css=\".vc_custom_1507730595411{margin-top: -0.3rem !important;}\"]<div class=\"sc_testimonials color_style_default sc_testimonials_default\"><div class=\"sc_testimonials_slider sc_item_slider slider_swiper_outer slider_outer slider_outer_nocontrols slider_outer_nopagination slider_outer_one\">\n\t<div class=\"slider_container swiper-slider-container slider_swiper slider_noresize slider_nocontrols slider_nopagination slider_one\" data-slides-min-width=\"290\" data-pagination=\"bullets\">\n\t\t<div class=\"slides slider-wrapper swiper-wrapper sc_item_columns_1\"><div class=\"slider-slide swiper-slide\"><div class=\"sc_testimonials_item\">\n\t<div class=\"sc_testimonials_item_content\"><p>Muito obrigada a equipe fiquei muito satisfeita com o trabalho de voc\u00eas!<\/p>\n<\/div>\n\t<div class=\"sc_testimonials_item_author\">\n\t\t\t\t<div class=\"sc_testimonials_item_author_data\">\n\t\t\t<h4 class=\"sc_testimonials_item_author_title\">Cleuza Nascimento<\/h4>\n\t\t\t<div class=\"sc_testimonials_item_author_subtitle\"><\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div><div class=\"slider-slide swiper-slide\"><div class=\"sc_testimonials_item\">\n\t<div class=\"sc_testimonials_item_content\"><p>Pessoas altamente qualificadas e produtos de m\u00e1xima qualidade. Gostei muito e certamente recomendo, materiais de alta qualidade.<\/p>\n<\/div>\n\t<div class=\"sc_testimonials_item_author\">\n\t\t\t\t<div class=\"sc_testimonials_item_author_data\">\n\t\t\t<h4 class=\"sc_testimonials_item_author_title\">Jorge Fernandes<\/h4>\n\t\t\t<div class=\"sc_testimonials_item_author_subtitle\"><\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div><div class=\"slider-slide swiper-slide\"><div class=\"sc_testimonials_item\">\n\t<div class=\"sc_testimonials_item_content\"><p>Excelente empresa, tem um belo atendimento, e uma ampla variedades de uniformes de \u00f3tima qualidade com bordados e serigrafia que impressionam. Super recomendo!<\/p>\n<\/div>\n\t<div class=\"sc_testimonials_item_author\">\n\t\t\t\t<div class=\"sc_testimonials_item_author_data\">\n\t\t\t<h4 class=\"sc_testimonials_item_author_title\">Luis Dias<\/h4>\n\t\t\t<div class=\"sc_testimonials_item_author_subtitle\"><\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div><\/div><\/div><\/div><\/div><!-- \/.sc_testimonials -->[\/vc_column_inner][vc_column_inner width=\"5\/6\" icons_position=\"left\" offset=\"vc_hidden-md vc_col-sm-offset-2 vc_hidden-sm vc_hidden-xs\"][vc_empty_space alter_height=\"small\" hide_on_desktop=\"1\" hide_on_notebook=\"\" hide_on_tablet=\"\" hide_on_mobile=\"\"][\/vc_column_inner][\/vc_row_inner][vc_empty_space alter_height=\"medium\" hide_on_desktop=\"1\" hide_on_notebook=\"1\" hide_on_tablet=\"1\" hide_on_mobile=\"\"]<\/div><\/div><!-- \/.sc_content -->[\/vc_column][\/vc_row]<\/div>[\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row_content_no_spaces&#8221;][vc_column][vc_column_text]<iframe loading=\"lazy\" style=\"border: 0;\" src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m18!1m12!1m3!1d3898.972592029199!2d-38.96618788548282!3d-12.250133991332069!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0x714378c592fb87f%3A0xf328f461a2ed7523!2sSoft%20Fardamentos!5e0!3m2!1spt-BR!2sbr!4v1662806415002!5m2!1spt-BR!2sbr\" width=\"100%\" height=\"450\" allowfullscreen=\"allowfullscreen\"><\/iframe>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row full_width=&#8221;stretch_row_content_no_spaces&#8221; hide_bg_image_on_tablet=&#8221;&#8221; hide_bg_image_on_mobile=&#8221;&#8221;][vc_column][rev_slider_vc alias=&#8221;home-1&#8243;][\/vc_column][\/vc_row][vc_row content_placement=&#8221;middle&#8221; hide_bg_image_on_tablet=&#8221;&#8221; hide_bg_image_on_mobile=&#8221;&#8221;][vc_column][\/vc_column][\/vc_row][vc_row content_placement=&#8221;middle&#8221; hide_bg_image_on_tablet=&#8221;&#8221; hide_bg_image_on_mobile=&#8221;&#8221;][vc_column][\/vc_column][\/vc_row][vc_row][vc_column][vc_empty_space alter_height=&#8221;huge&#8221; hide_on_desktop=&#8221;&#8221; hide_on_notebook=&#8221;&#8221; hide_on_tablet=&#8221;&#8221; hide_on_mobile=&#8221;&#8221;][\/vc_column][\/vc_row][vc_row content_placement=&#8221;middle&#8221; hide_bg_image_on_tablet=&#8221;&#8221; hide_bg_image_on_mobile=&#8221;&#8221;][vc_column hide_bg_image_on_tablet=&#8221;&#8221; hide_bg_image_on_mobile=&#8221;&#8221;][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row_content_no_spaces&#8221;][vc_column][vc_column_text][\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-90","page","type-page","status-publish","hentry"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/softfardamentos.com.br\/index.php\/wp-json\/wp\/v2\/pages\/90"}],"collection":[{"href":"https:\/\/softfardamentos.com.br\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/softfardamentos.com.br\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/softfardamentos.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/softfardamentos.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=90"}],"version-history":[{"count":7,"href":"https:\/\/softfardamentos.com.br\/index.php\/wp-json\/wp\/v2\/pages\/90\/revisions"}],"predecessor-version":[{"id":890,"href":"https:\/\/softfardamentos.com.br\/index.php\/wp-json\/wp\/v2\/pages\/90\/revisions\/890"}],"wp:attachment":[{"href":"https:\/\/softfardamentos.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=90"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}